{"id":378,"date":"2023-10-01T16:35:38","date_gmt":"2023-10-01T16:35:38","guid":{"rendered":"https:\/\/sugrobov.de\/?p=378"},"modified":"2023-10-07T16:40:14","modified_gmt":"2023-10-07T16:40:14","slug":"abnahme-als-faelligkeitsvoraussetzung-nach-hoai-2013-wann-liegt-sie-vor","status":"publish","type":"post","link":"https:\/\/sugrobov.de\/ru\/abnahme-als-faelligkeitsvoraussetzung-nach-hoai-2013-wann-liegt-sie-vor\/","title":{"rendered":"\u041f\u0440\u0438\u0435\u043c\u043a\u0430 \u043a\u0430\u043a \u0443\u0441\u043b\u043e\u0432\u0438\u0435 \u0441\u0440\u043e\u043a\u043d\u043e\u0441\u0442\u0438 \u043f\u043e HOAI 2013: \u041a\u043e\u0433\u0434\u0430 \u044d\u0442\u043e \u043f\u0440\u043e\u0438\u0441\u0445\u043e\u0434\u0438\u0442?"},"content":{"rendered":"<p>\u0415\u0441\u043b\u0438 \u043a\u043b\u0438\u0435\u043d\u0442 \u0437\u0430\u043d\u0438\u043c\u0430\u0435\u0442 \u0437\u0434\u0430\u043d\u0438\u0435 \u0438 \u043d\u0435 \u043f\u0440\u043e\u044f\u0432\u043b\u044f\u0435\u0442 \u043f\u0440\u043e\u0442\u0438\u0432\u043e\u0440\u0435\u0447\u0438\u0432\u043e\u0433\u043e \u043f\u043e\u0432\u0435\u0434\u0435\u043d\u0438\u044f \u043f\u043e\u0441\u043b\u0435 \u0440\u0430\u0437\u0443\u043c\u043d\u043e\u0433\u043e \u0441\u0440\u043e\u043a\u0430 \u043f\u0440\u043e\u0432\u0435\u0440\u043a\u0438, \u044d\u0442\u043e \u043c\u043e\u0436\u043d\u043e \u0440\u0430\u0441\u0441\u043c\u0430\u0442\u0440\u0438\u0432\u0430\u0442\u044c \u043a\u0430\u043a \u043c\u043e\u043b\u0447\u0430\u043b\u0438\u0432\u043e\u0435 \u043f\u0440\u0438\u043d\u044f\u0442\u0438\u0435. \u0414\u043b\u044f \u043e\u0434\u043d\u043e\u0441\u0435\u043c\u0435\u0439\u043d\u043e\u0433\u043e \u0434\u043e\u043c\u0430 \u0441\u0440\u043e\u043a \u043f\u0440\u043e\u0432\u0435\u0440\u043a\u0438 \u043e\u043a\u043e\u043b\u043e 6 \u043c\u0435\u0441\u044f\u0446\u0435\u0432 \u0441\u0447\u0438\u0442\u0430\u0435\u0442\u0441\u044f \u043f\u0440\u0438\u0435\u043c\u043b\u0435\u043c\u044b\u043c.<\/p>\n<p><strong>\u0424\u043e\u043d:<\/strong> \u0410\u0440\u0445\u0438\u0442\u0435\u043a\u0442\u043e\u0440 \u043d\u0435\u0441\u0435\u0442 \u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0441\u0442\u044c \u0437\u0430 \u043d\u0430\u0440\u0443\u0448\u0435\u043d\u0438\u0435 \u0434\u043e\u0433\u043e\u0432\u043e\u0440\u043d\u044b\u0445 \u0438\u043b\u0438 \u0438\u043d\u044b\u0445 \u043e\u0431\u044f\u0437\u0430\u0442\u0435\u043b\u044c\u0441\u0442\u0432. \u041f\u0440\u0435\u0442\u0435\u043d\u0437\u0438\u0438 \u043a \u0430\u0440\u0445\u0438\u0442\u0435\u043a\u0442\u043e\u0440\u0443 \u043f\u043e\u0434\u043b\u0435\u0436\u0430\u0442 \u0434\u0430\u0432\u043d\u043e\u0441\u0442\u0438. \u041f\u043e\u043b\u043e\u0436\u0435\u043d\u0438\u044f \u043e \u043f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u0438, \u043d\u0430\u0447\u0430\u043b\u0435 \u0438 \u043f\u0440\u0435\u0440\u044b\u0432\u0430\u043d\u0438\u044f\u0445 \u0441\u0440\u043e\u043a\u0430 \u0434\u0430\u0432\u043d\u043e\u0441\u0442\u0438 \u043e\u0442\u043b\u0438\u0447\u0430\u043b\u0438\u0441\u044c \u0434\u043e 31.12.2001 \u043e\u0442 \u0431\u043e\u043b\u0435\u0435 \u043d\u043e\u0432\u043e\u0433\u043e \u0437\u0430\u043a\u043e\u043d\u0430.<\/p>\n<p><strong>\u041f\u0440\u0438\u043c\u0435\u0440:<\/strong> (\u043f\u043e \u0434\u0430\u043d\u043d\u044b\u043c OLG Celle, \u0440\u0435\u0448\u0435\u043d\u0438\u0435 \u043e\u0442 02.08.2023 &#8212; 14 U 200\/19) \u0410\u0440\u0445\u0438\u0442\u0435\u043a\u0442\u043e\u0440\u0443 \u043f\u043e\u0440\u0443\u0447\u0435\u043d\u043e \u0440\u0435\u043a\u043e\u043d\u0441\u0442\u0440\u0443\u0438\u0440\u043e\u0432\u0430\u0442\u044c \u0438 \u043c\u043e\u0434\u0435\u0440\u043d\u0438\u0437\u0438\u0440\u043e\u0432\u0430\u0442\u044c \u043e\u0434\u043d\u043e\u0441\u0435\u043c\u0435\u0439\u043d\u044b\u0439 \u0434\u043e\u043c. \u041f\u043e\u0437\u0436\u0435 \u043c\u0435\u0436\u0434\u0443 \u0434\u0432\u0443\u043c\u044f \u0441\u0442\u043e\u0440\u043e\u043d\u0430\u043c\u0438 \u0432\u043e\u0437\u043d\u0438\u043a\u0430\u044e\u0442 \u0440\u0430\u0437\u043d\u043e\u0433\u043b\u0430\u0441\u0438\u044f, \u0438 \u0430\u0440\u0445\u0438\u0442\u0435\u043a\u0442\u043e\u0440 \u0442\u0440\u0435\u0431\u0443\u0435\u0442 \u043e\u0441\u0442\u0430\u0432\u0448\u0438\u0439\u0441\u044f \u0433\u043e\u043d\u043e\u0440\u0430\u0440 \u043e\u0442 \u0441\u0442\u0440\u043e\u0438\u0442\u0435\u043b\u044f. \u0421\u0442\u0440\u043e\u0438\u0442\u0435\u043b\u044c \u0443\u0442\u0432\u0435\u0440\u0436\u0434\u0430\u0435\u0442, \u0447\u0442\u043e \u0442\u0440\u0435\u0431\u043e\u0432\u0430\u043d\u0438\u0435 \u0443\u0436\u0435 \u043f\u0440\u043e\u0432\u0430\u043b\u0438\u0432\u0430\u0435\u0442\u0441\u044f \u0438\u0437-\u0437\u0430 \u043e\u0442\u0441\u0443\u0442\u0441\u0442\u0432\u0438\u044f \u0441\u0440\u043e\u043a\u043d\u043e\u0441\u0442\u0438 \u0433\u043e\u043d\u043e\u0440\u0430\u0440\u0430 \u0432 \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0438\u0438 \u0441 \u00a7 15 I HOAI 2013: \u043e\u043d \u043d\u0435 \u043f\u0440\u0438\u043d\u044f\u043b \u0430\u0440\u0445\u0438\u0442\u0435\u043a\u0442\u0443\u0440\u043d\u0443\u044e \u0440\u0430\u0431\u043e\u0442\u0443, \u0438 \u044d\u0442\u043e \u043f\u0440\u0438\u043d\u044f\u0442\u0438\u0435 \u044f\u0432\u043b\u044f\u0435\u0442\u0441\u044f \u043f\u0440\u0435\u0434\u0432\u0430\u0440\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u043c \u0443\u0441\u043b\u043e\u0432\u0438\u0435\u043c \u0434\u043b\u044f \u0441\u0440\u043e\u043a\u043d\u043e\u0441\u0442\u0438 \u043f\u043e \u00a7 15 HOAI 2013. \u041e\u043d \u0442\u0430\u043a\u0436\u0435 \u043f\u043e\u0434\u0447\u0435\u0440\u043a\u0438\u0432\u0430\u0435\u0442, \u0447\u0442\u043e \u043f\u0440\u0438\u0435\u043c\u043a\u0430 \u0441\u0442\u0440\u043e\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0445 \u0443\u0441\u043b\u0443\u0433 \u043d\u0435 \u0434\u043e\u043b\u0436\u043d\u0430 \u043f\u0443\u0442\u0430\u0442\u044c\u0441\u044f \u0441 \u043f\u0440\u0438\u0435\u043c\u043a\u043e\u0439 \u0430\u0440\u0445\u0438\u0442\u0435\u043a\u0442\u0443\u0440\u043d\u044b\u0445 \u0443\u0441\u043b\u0443\u0433.<\/p>\n<p>\u041e\u0431\u0430 \u0441\u0443\u0434\u0430 &#8212; \u043e\u043a\u0440\u0443\u0436\u043d\u043e\u0439 \u0438 \u0432\u044b\u0441\u0448\u0438\u0439 \u043e\u043a\u0440\u0443\u0436\u043d\u043e\u0439 &#8212; \u0432\u044b\u0441\u043a\u0430\u0437\u044b\u0432\u0430\u044e\u0442 \u0438\u043d\u043e\u0435 \u043c\u043d\u0435\u043d\u0438\u0435 \u0438 \u0432\u0438\u0434\u044f\u0442 \u0441\u0440\u043e\u043a\u043d\u043e\u0441\u0442\u044c \u0442\u0440\u0435\u0431\u043e\u0432\u0430\u043d\u0438\u044f \u043e \u0433\u043e\u043d\u043e\u0440\u0430\u0440\u0435 \u043a\u0430\u043a \u0434\u0430\u043d\u043d\u043e\u0441\u0442\u044c. \u041e\u043d\u0438 \u043f\u0440\u0435\u0434\u043f\u043e\u043b\u0430\u0433\u0430\u044e\u0442 \u043c\u043e\u043b\u0447\u0430\u043b\u0438\u0432\u043e\u0435 \u043f\u0440\u0438\u043d\u044f\u0442\u0438\u0435 \u0430\u0440\u0445\u0438\u0442\u0435\u043a\u0442\u0443\u0440\u043d\u043e\u0439 \u0440\u0430\u0431\u043e\u0442\u044b, \u043a\u043e\u0442\u043e\u0440\u043e\u0435 \u043f\u0440\u043e\u0438\u0437\u043e\u0448\u043b\u043e \u0432\u043e \u0432\u0440\u0435\u043c\u044f \u0437\u0430\u0441\u0435\u043b\u0435\u043d\u0438\u044f \u0437\u0434\u0430\u043d\u0438\u044f. \u0412 \u0446\u0435\u043b\u043e\u043c \u043c\u043e\u043b\u0447\u0430\u043b\u0438\u0432\u043e\u0435 \u0436\u0435\u043b\u0430\u043d\u0438\u0435 \u043f\u0440\u0438\u043d\u044f\u0442\u044c \u043c\u043e\u0436\u043d\u043e \u043f\u0440\u0435\u0434\u043f\u043e\u043b\u043e\u0436\u0438\u0442\u044c \u0442\u043e\u043b\u044c\u043a\u043e \u0432 \u0442\u043e\u043c \u0441\u043b\u0443\u0447\u0430\u0435, \u0435\u0441\u043b\u0438 \u0443 \u043a\u043b\u0438\u0435\u043d\u0442\u0430 \u0431\u044b\u043b\u043e \u0434\u043e\u0441\u0442\u0430\u0442\u043e\u0447\u043d\u043e \u0432\u0440\u0435\u043c\u0435\u043d\u0438 \u0434\u043b\u044f \u043f\u0440\u043e\u0432\u0435\u0440\u043a\u0438 \u0440\u0430\u0431\u043e\u0442\u044b. \u041f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u044c \u044d\u0442\u043e\u0433\u043e \u043f\u0435\u0440\u0438\u043e\u0434\u0430 \u043f\u0440\u043e\u0432\u0435\u0440\u043a\u0438 \u0438 \u043e\u0446\u0435\u043d\u043a\u0438 \u0437\u0430\u0432\u0438\u0441\u0438\u0442 \u043e\u0442 \u043a\u043e\u043d\u043a\u0440\u0435\u0442\u043d\u043e\u0433\u043e \u0441\u043b\u0443\u0447\u0430\u044f \u0438 \u043e\u043f\u0440\u0435\u0434\u0435\u043b\u044f\u0435\u0442\u0441\u044f \u043e\u0431\u0449\u0438\u043c\u0438 \u043e\u0436\u0438\u0434\u0430\u043d\u0438\u044f\u043c\u0438. \u0421 \u0443\u0447\u0435\u0442\u043e\u043c \u0437\u0430\u043a\u043e\u043d\u043d\u044b\u0445 \u0438\u043d\u0442\u0435\u0440\u0435\u0441\u043e\u0432 \u0430\u0440\u0445\u0438\u0442\u0435\u043a\u0442\u043e\u0440\u0430 \u0431\u044b\u043b\u043e \u0431\u044b \u043d\u0435\u0441\u043f\u0440\u0430\u0432\u0435\u0434\u043b\u0438\u0432\u043e \u0431\u0435\u0441\u043a\u043e\u043d\u0435\u0447\u043d\u043e \u043f\u0440\u043e\u0434\u043b\u0435\u0432\u0430\u0442\u044c \u043f\u0435\u0440\u0438\u043e\u0434 \u043f\u0440\u043e\u0432\u0435\u0440\u043a\u0438.<\/p>\n<p><strong>\u041f\u0440\u0438\u043c\u0435\u0447\u0430\u043d\u0438\u0435:<\/strong> \u041d\u0430 \u0444\u043e\u043d\u0435 \u0432\u044b\u0448\u0435\u0443\u043a\u0430\u0437\u0430\u043d\u043d\u043e\u0439 \u0441\u0443\u0434\u0435\u0431\u043d\u043e\u0439 \u043f\u0440\u0430\u043a\u0442\u0438\u043a\u0438 \u043c\u043e\u0436\u043d\u043e \u043f\u0440\u0435\u0434\u043f\u043e\u043b\u043e\u0436\u0438\u0442\u044c, \u0447\u0442\u043e \u0434\u043b\u044f \u043a\u0440\u0443\u043f\u043d\u044b\u0445 \u0441\u0442\u0440\u043e\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0445 \u043f\u0440\u043e\u0435\u043a\u0442\u043e\u0432, \u043e\u0442\u043b\u0438\u0447\u043d\u044b\u0445 \u043e\u0442 \u043e\u0434\u043d\u043e\u0441\u0435\u043c\u0435\u0439\u043d\u044b\u0445 \u0434\u043e\u043c\u043e\u0432, \u043c\u043e\u0436\u0435\u0442 \u043f\u043e\u0442\u0440\u0435\u0431\u043e\u0432\u0430\u0442\u044c\u0441\u044f \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0443\u044e\u0449\u0438\u0439 \u0440\u0430\u0441\u0448\u0438\u0440\u0435\u043d\u043d\u044b\u0439 \u043f\u0435\u0440\u0438\u043e\u0434 \u043f\u0440\u043e\u0432\u0435\u0440\u043a\u0438. \u0422\u0435\u043c \u043d\u0435 \u043c\u0435\u043d\u0435\u0435, \u0432\u0441\u0435\u0433\u0434\u0430 \u043d\u0435\u043e\u0431\u0445\u043e\u0434\u0438\u043c\u043e \u043f\u0440\u043e\u0432\u0435\u0440\u044f\u0442\u044c, \u043d\u0435 \u043d\u0430\u0441\u0442\u0443\u043f\u0438\u043b\u0430 \u043b\u0438 \u0441\u0440\u043e\u043a\u043d\u043e\u0441\u0442\u044c \u0433\u043e\u043d\u043e\u0440\u0430\u0440\u0430 \u0438\u0437-\u0437\u0430 \u0437\u0430\u043c\u0435\u043d\u044b \u043d\u0430 \u043f\u0440\u0438\u0435\u043c\u043a\u0443 (\u043d\u0430\u043f\u0440\u0438\u043c\u0435\u0440, \u043d\u0430\u0447\u0430\u043b\u043e \u0443\u0440\u0435\u0433\u0443\u043b\u0438\u0440\u043e\u0432\u0430\u043d\u0438\u044f \u043e\u0442\u043d\u043e\u0448\u0435\u043d\u0438\u0439).<\/p>","protected":false},"excerpt":{"rendered":"<p>\u0415\u0441\u043b\u0438 \u043a\u043b\u0438\u0435\u043d\u0442 \u0437\u0430\u043d\u0438\u043c\u0430\u0435\u0442 \u0437\u0434\u0430\u043d\u0438\u0435 \u0438 \u043d\u0435 \u043f\u0440\u043e\u044f\u0432\u043b\u044f\u0435\u0442 \u043f\u0440\u043e\u0442\u0438\u0432\u043e\u0440\u0435\u0447\u0438\u0432\u043e\u0433\u043e \u043f\u043e\u0432\u0435\u0434\u0435\u043d\u0438\u044f \u043f\u043e\u0441\u043b\u0435 \u0440\u0430\u0437\u0443\u043c\u043d\u043e\u0433\u043e \u0441\u0440\u043e\u043a\u0430 \u043f\u0440\u043e\u0432\u0435\u0440\u043a\u0438, \u044d\u0442\u043e \u043c\u043e\u0436\u043d\u043e \u0440\u0430\u0441\u0441\u043c\u0430\u0442\u0440\u0438\u0432\u0430\u0442\u044c \u043a\u0430\u043a \u043c\u043e\u043b\u0447\u0430\u043b\u0438\u0432\u043e\u0435 \u043f\u0440\u0438\u043d\u044f\u0442\u0438\u0435. \u0414\u043b\u044f \u043e\u0434\u043d\u043e\u0441\u0435\u043c\u0435\u0439\u043d\u043e\u0433\u043e \u0434\u043e\u043c\u0430 \u0441\u0440\u043e\u043a \u043f\u0440\u043e\u0432\u0435\u0440\u043a\u0438 \u043e\u043a\u043e\u043b\u043e 6 \u043c\u0435\u0441\u044f\u0446\u0435\u0432 \u0441\u0447\u0438\u0442\u0430\u0435\u0442\u0441\u044f \u043f\u0440\u0438\u0435\u043c\u043b\u0435\u043c\u044b\u043c. \u0424\u043e\u043d: \u0410\u0440\u0445\u0438\u0442\u0435\u043a\u0442\u043e\u0440 \u043d\u0435\u0441\u0435\u0442 \u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0435\u043d\u043d\u043e\u0441\u0442\u044c \u0437\u0430 \u043d\u0430\u0440\u0443\u0448\u0435\u043d\u0438\u0435 \u0434\u043e\u0433\u043e\u0432\u043e\u0440\u043d\u044b\u0445 \u0438\u043b\u0438 \u0438\u043d\u044b\u0445 \u043e\u0431\u044f\u0437\u0430\u0442\u0435\u043b\u044c\u0441\u0442\u0432. \u041f\u0440\u0435\u0442\u0435\u043d\u0437\u0438\u0438 \u043a \u0430\u0440\u0445\u0438\u0442\u0435\u043a\u0442\u043e\u0440\u0443 \u043f\u043e\u0434\u043b\u0435\u0436\u0430\u0442 \u0434\u0430\u0432\u043d\u043e\u0441\u0442\u0438. \u041f\u043e\u043b\u043e\u0436\u0435\u043d\u0438\u044f \u043e \u043f\u0440\u043e\u0434\u043e\u043b\u0436\u0438\u0442\u0435\u043b\u044c\u043d\u043e\u0441\u0442\u0438, \u043d\u0430\u0447\u0430\u043b\u0435 \u0438 \u043f\u0440\u0435\u0440\u044b\u0432\u0430\u043d\u0438\u044f\u0445 \u0441\u0440\u043e\u043a\u0430 \u0434\u0430\u0432\u043d\u043e\u0441\u0442\u0438 \u043e\u0442\u043b\u0438\u0447\u0430\u043b\u0438\u0441\u044c \u0434\u043e 31.12.2001 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-378","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"acf":[],"_links":{"self":[{"href":"https:\/\/sugrobov.de\/ru\/wp-json\/wp\/v2\/posts\/378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sugrobov.de\/ru\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sugrobov.de\/ru\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sugrobov.de\/ru\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sugrobov.de\/ru\/wp-json\/wp\/v2\/comments?post=378"}],"version-history":[{"count":2,"href":"https:\/\/sugrobov.de\/ru\/wp-json\/wp\/v2\/posts\/378\/revisions"}],"predecessor-version":[{"id":381,"href":"https:\/\/sugrobov.de\/ru\/wp-json\/wp\/v2\/posts\/378\/revisions\/381"}],"wp:attachment":[{"href":"https:\/\/sugrobov.de\/ru\/wp-json\/wp\/v2\/media?parent=378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sugrobov.de\/ru\/wp-json\/wp\/v2\/categories?post=378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sugrobov.de\/ru\/wp-json\/wp\/v2\/tags?post=378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}